{"id":61337,"date":"2026-02-20T11:50:50","date_gmt":"2026-02-20T11:50:50","guid":{"rendered":"https:\/\/espacetriathlon.com\/product\/apex-viper-donna\/"},"modified":"2026-02-20T11:50:50","modified_gmt":"2026-02-20T11:50:50","slug":"apex-viper-donna","status":"publish","type":"product","link":"https:\/\/espacetriathlon.com\/it\/product\/apex-viper-donna\/","title":{"rendered":"Apex Viper Donna"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Costume da bagno da competizione entry level<\/p>\n<p>Appositamente progettate per introdurti a un nuovo livello di prestazioni, le Viper, approvate da World Aquatics, offrono una vestibilit\u00e0 salda per facilitare i movimenti in acqua.<\/p>\n<ul>\n<li>Il tessuto a maglia indemagliabile si modella sul corpo per aiutare l&#8217;affaticamento muscolare grazie a una compressione di medio livello.<\/li>\n<li>Abbinata a una finitura idrorepellente, questa tuta ti lancer\u00e0 verso il livello successivo e oltre.<\/li>\n<li>Le caratteristiche includono: Cuciture flatlock per il massimo comfort, cordoncino integrato, fodera modesty compressiva, nastro di presa in vita e all&#8217;apertura delle gambe per una vestibilit\u00e0 sicura e confortevole.<\/li>\n<\/ul>\n<p>Approvato da World Aquatics<\/p>\n<p>Funkita \/ Openback<\/p>\n<p>Controlla le immagini per determinare la tua taglia<\/p>\n","protected":false},"featured_media":61328,"template":"","meta":[],"product_brand":[],"product_cat":[1740],"product_tag":[],"class_list":["post-61337","product","type-product","status-publish","has-post-thumbnail","product_cat-race-suits-it","product_shipping_class-petitarticle-it","pa_apex-2821","pa_apex-2825","pa_apex-2829","pa_apex-2832","pa_apex-2835","pa_brand-funkita-it","first","instock","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/espacetriathlon.com\/it\/wp-json\/wp\/v2\/product\/61337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacetriathlon.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/espacetriathlon.com\/it\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/espacetriathlon.com\/it\/wp-json\/wp\/v2\/product\/61337\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacetriathlon.com\/it\/wp-json\/wp\/v2\/media\/61328"}],"wp:attachment":[{"href":"https:\/\/espacetriathlon.com\/it\/wp-json\/wp\/v2\/media?parent=61337"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/espacetriathlon.com\/it\/wp-json\/wp\/v2\/product_brand?post=61337"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/espacetriathlon.com\/it\/wp-json\/wp\/v2\/product_cat?post=61337"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/espacetriathlon.com\/it\/wp-json\/wp\/v2\/product_tag?post=61337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}