{"id":69268,"date":"2026-07-21T16:52:28","date_gmt":"2026-07-21T16:52:28","guid":{"rendered":"https:\/\/espacetriathlon.com\/product\/carbon-glide-jammer-nero\/"},"modified":"2026-07-21T16:52:28","modified_gmt":"2026-07-21T16:52:28","slug":"carbon-glide-jammer-nero","status":"publish","type":"product","link":"https:\/\/espacetriathlon.com\/it\/product\/carbon-glide-jammer-nero\/","title":{"rendered":"Carbon Glide Jammer Nero"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<div class=\"widget block block-static-block\">\n<div data-content-type=\"row\" data-appearance=\"contained\" data-element=\"main\">\n<div data-enable-parallax=\"0\" data-parallax-speed=\"0.5\" data-background-images=\"{}\" data-background-type=\"image\" data-video-loop=\"true\" data-video-play-only-visible=\"true\" data-video-lazy-load=\"true\" data-video-fallback-src=\"\" data-element=\"inner\" data-pb-style=\"SX0T7SC\">\n<div data-content-type=\"text\" data-appearance=\"default\" data-element=\"main\">\n<p><em>Carbon Glide \u00e8 una tuta leggerissima ed \u00e8 proprio per questo che piace a cos\u00ec tante persone. Tuttavia, proprio questa leggerezza la rende particolarmente delicata quando la indossi. Assicurati che le tue unghie non tocchino il tessuto. E tirala sempre dalle cuciture, non dal tessuto.   <\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>Quando parti dai blocchi e ti lanci in gara, senti subito la sensazione di fluidit\u00e0 con il nostro nuovissimo costume tecnico da uomo. I nostri Powerskin Carbon Glide Jammers sono pensati per i nuotatori che cercano la sensazione di velocit\u00e0 nel costume con cui gareggiano. Realizzati con il tessuto ultraleggero Hydroglide, questi costumi riducono efficacemente la resistenza e le turbolenze. Inserti strategici in tessuto a rete di carbonio compatto e nastri interni comprimono e attivano immediatamente i muscoli. Progettato dentro e fuori per una superficie aerodinamica, un corpo pieno di energia e una nuotata senza intoppi.    <\/p>\n","protected":false},"featured_media":69257,"template":"","meta":[],"product_brand":[],"product_cat":[1740],"product_tag":[],"class_list":["post-69268","product","type-product","status-publish","has-post-thumbnail","product_cat-race-suits-it","pa_brand-arena-it-2","pa_carbon_h-d2-f70-uk28","pa_carbon_h-d3-f75-uk30","first","instock","sale","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/espacetriathlon.com\/it\/wp-json\/wp\/v2\/product\/69268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacetriathlon.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/espacetriathlon.com\/it\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/espacetriathlon.com\/it\/wp-json\/wp\/v2\/product\/69268\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacetriathlon.com\/it\/wp-json\/wp\/v2\/media\/69257"}],"wp:attachment":[{"href":"https:\/\/espacetriathlon.com\/it\/wp-json\/wp\/v2\/media?parent=69268"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/espacetriathlon.com\/it\/wp-json\/wp\/v2\/product_brand?post=69268"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/espacetriathlon.com\/it\/wp-json\/wp\/v2\/product_cat?post=69268"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/espacetriathlon.com\/it\/wp-json\/wp\/v2\/product_tag?post=69268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}